{"id":3740,"date":"2022-11-30T10:30:00","date_gmt":"2022-11-30T09:30:00","guid":{"rendered":"https:\/\/dev.noratech.it\/vallibitto\/?p=3740"},"modified":"2022-09-07T14:43:16","modified_gmt":"2022-09-07T12:43:16","slug":"paolo-ciapparelli-raccontala-necessita-di-ribellarsi","status":"publish","type":"post","link":"https:\/\/storicoribelle.com\/en\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/","title":{"rendered":"Paolo Ciapparelli racconta:<br>La necessit\u00e0 di ribellarsi"},"content":{"rendered":"<div>\n<p><em><span style=\"font-weight: 400; color:#000;\">Esistono diverse forme di ribellione: per non spaventare nessuno, \u00e8 ora di chiarire la causa per cui siamo stati chiamati \u201ceversivi\u201d.\u00a0<\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color:#000;\">Quando ancora nel XX secolo ho avuto l\u2019intuizione dell\u2019importanza di difendere l\u2019alpeggio con metodo storico, pensavo bisognasse partire da un semplice concetto, che agli occhi di tutti sembrava scontato: le vacche in alpeggio devono mangiare solo erba.<\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color:#000;\">Ebbene s\u00ec, ho guidato un movimento eversivo perch\u00e9 opponendomi a mangimi e fermenti ho sfidato l\u2019industria, per preservare quel poco che restava di artigianalit\u00e0 nel nostro mondo, ben sapendo che senza una presa di posizione ufficiale sarebbe scomparso il sistema di pascolo tradizionale.<\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color:#000;\">L\u2019opposizione che ho fatto a nome dei produttori storici, anche sulla Gazzetta Ufficiale italiana e poi come ricorso alla Commissione Europea, pur condotta con metodi dilettantistici (gli avvocati costano!) \u00e8 stato un gesto coraggioso e fuori dal coro. Prima di noi nessuno aveva denunciato questa tendenza nel mondo caseario!\u00a0<\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color:#000;\">Oggi l&#8217;agricoltura green \u00e8 al centro dei progetti futuri, da Greta Thunberg (che non era ancora nata quando abbiamo iniziato le nostre battaglie) al Recovery Fund, ci sono fondi destinati a chi dovrebbe costruire un futuro rispettando l\u2019ambiente. Siamo per\u00f2 certi che questo modello di sviluppo lo potr\u00e0 guidare chi fino ad oggi \u00e8 stato paladino dell\u2019agricoltura intensiva, che si traduce in fermenti e mangimi in alpeggio, con lo scopo di standardizzare le produzioni e aumentarne le quantit\u00e0? A noi sembra il caso delle tante DOP, che a colpi di modifiche nei disciplinari, hanno distrutto produzioni storiche facendole finire nelle mani dell\u2019agro-industria.<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400; color:#000;\"><em style=\"color:#000;\">Ecco perch\u00e9 ho guidato questo tentativo eversivo, ma ho il sospetto che questa volta non baster\u00e0 il solito Paolo Ciapparelli a difendere i pochi caricatori d\u2019alpe tradizionali rimasti&#8230;<\/em> <\/span><\/p>\n<\/div>\n<h2>Articoli che potrebbero interessarti<\/h2>\n<div>\n<\/div>\n<p>\n    <a href=\"\/vallibitto\/news-ed-eventi\/\">Vedi tutte le News<\/a>\n<\/p>\n<p><!--more--><br \/>\n<!-- {\"name\":\"PAGINA-NEWS\",\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"large\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding_remove_bottom\":false,\"animation\":\"fade\"},\"children\":[{\"type\":\"row\",\"props\":{\"width\":\"xsmall\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"text_align\":\"center\",\"margin\":\"default\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\"},\"props\":{\"content\":{\"filters\":{\"search\":\"\"},\"name\":\"title\"}}}},{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"text_align\":\"center\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\"},\"props\":{\"content\":{\"filters\":{\"search\":\"\",\"date\":\"\"},\"name\":\"date\"}}}}]}]},{\"type\":\"row\",\"props\":{\"width\":\"large\",\"margin\":\"large\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image_width\":\"1400\",\"image_height\":\"700\",\"animation\":\"none\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\"},\"props\":{\"image\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.url\"},\"image_alt\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.alt\"}}}}]}]},{\"type\":\"row\",\"props\":{\"width\":\"default\",\"margin\":\"large\",\"layout\":\"2-3,1-3\",\"padding_remove_horizontal\":false,\"column_gap\":\"large\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"2-3\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"medium\",\"column_breakpoint\":\"m\",\"animation\":\"none\",\"content\":\"\n\n<p><em><span style=\\\"font-weight: 400; color:#000;\\\">Esistono diverse forme di ribellione: per non spaventare nessuno, \\u00e8 ora di chiarire la causa per cui siamo stati chiamati \\u201ceversivi\\u201d.\\u00a0<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color:#000;\\\">Quando ancora nel XX secolo ho avuto l\\u2019intuizione dell\\u2019importanza di difendere l\\u2019alpeggio con metodo storico, pensavo bisognasse partire da un semplice concetto, che agli occhi di tutti sembrava scontato: le vacche in alpeggio devono mangiare solo erba.<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color:#000;\\\">Ebbene s\\u00ec, ho guidato un movimento eversivo perch\\u00e9 opponendomi a mangimi e fermenti ho sfidato l\\u2019industria, per preservare quel poco che restava di artigianalit\\u00e0 nel nostro mondo, ben sapendo che senza una presa di posizione ufficiale sarebbe scomparso il sistema di pascolo tradizionale.<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color:#000;\\\">L\\u2019opposizione che ho fatto a nome dei produttori storici, anche sulla Gazzetta Ufficiale italiana e poi come ricorso alla Commissione Europea, pur condotta con metodi dilettantistici (gli avvocati costano!) \\u00e8 stato un gesto coraggioso e fuori dal coro. Prima di noi nessuno aveva denunciato questa tendenza nel mondo caseario!\\u00a0<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color:#000;\\\">Oggi l'agricoltura green \\u00e8 al centro dei progetti futuri, da Greta Thunberg (che non era ancora nata quando abbiamo iniziato le nostre battaglie) al Recovery Fund, ci sono fondi destinati a chi dovrebbe costruire un futuro rispettando l\\u2019ambiente. Siamo per\\u00f2 certi che questo modello di sviluppo lo potr\\u00e0 guidare chi fino ad oggi \\u00e8 stato paladino dell\\u2019agricoltura intensiva, che si traduce in fermenti e mangimi in alpeggio, con lo scopo di standardizzare le produzioni e aumentarne le quantit\\u00e0? A noi sembra il caso delle tante DOP, che a colpi di modifiche nei disciplinari, hanno distrutto produzioni storiche facendole finire nelle mani dell\\u2019agro-industria.<\\\/span><\\\/em><\\\/p>\\n\n\n<p><span style=\\\"font-weight: 400; color:#000;\\\"><em style=\\\"color:#000;\\\">Ecco perch\\u00e9 ho guidato questo tentativo eversivo, ma ho il sospetto che questa volta non baster\\u00e0 il solito Paolo Ciapparelli a difendere i pochi caricatori d\\u2019alpe tradizionali rimasti...<\\\/em> <\\\/span><\\\/p>\",\"text_align\":\"left\",\"text_align_breakpoint\":\"m\",\"text_align_fallback\":\"justify\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-3\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Articoli che potrebbero interessarti\",\"title_style\":\"h4\",\"animation\":\"none\",\"_condition\":true,\"text_align\":\"left\",\"text_align_breakpoint\":\"m\",\"text_align_fallback\":\"center\",\"margin\":\"large\"}},{\"type\":\"grid\",\"props\":{\"show_title\":true,\"show_meta\":true,\"show_content\":true,\"show_image\":true,\"show_link\":true,\"grid_default\":\"1\",\"grid_medium\":\"1\",\"filter_style\":\"tab\",\"filter_all\":true,\"filter_position\":\"top\",\"filter_align\":\"left\",\"filter_grid_width\":\"auto\",\"filter_grid_breakpoint\":\"m\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"h6\",\"meta_align\":\"above-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"left\",\"image_grid_width\":\"auto\",\"image_grid_breakpoint\":\"\",\"image_svg_color\":\"emphasis\",\"link_text\":\"\",\"link_style\":\"default\",\"margin\":\"default\",\"item_animation\":true,\"grid_column_gap\":\"small\",\"image_width\":\"100\",\"image_grid_column_gap\":\"small\",\"image_vertical_align\":true,\"title_style\":\"h5\",\"meta_color\":\"primary\",\"title_margin\":\"remove\",\"grid_row_gap\":\"small\",\"panel_link\":false,\"grid_small\":\"2\",\"grid_divider\":true,\"title_link\":true,\"image_link\":true,\"animation\":\"none\",\"image_height\":\"70\"},\"children\":[{\"type\":\"grid_item\",\"source\":{\"query\":{\"name\":\"posts.customPosts\",\"arguments\":{\"terms\":[24],\"category_operator\":\"IN\",\"post_tag_operator\":\"IN\",\"users\":[],\"users_operator\":\"IN\",\"offset\":0,\"limit\":4,\"order\":\"rand\",\"order_direction\":\"DESC\"}},\"props\":{\"title\":{\"filters\":{\"search\":\"\"},\"name\":\"title\"},\"image\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.url\"},\"image_alt\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.alt\"},\"link\":{\"filters\":{\"search\":\"\"},\"name\":\"link\"}}}}],\"modified\":\"2020-12-14T10:54:26.407Z\",\"name\":\"\"},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"medium\",\"text_align\":\"left\",\"text_align_breakpoint\":\"m\",\"text_align_fallback\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"text\",\"icon_align\":\"right\",\"content\":\"Vedi tutte le News\",\"icon\":\"chevron-right\",\"link\":\"news-ed-eventi\\\/\"}}]}]}]}],\"name\":\"articolo\"}],\"version\":\"2.7.26\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esistono diverse forme di ribellione: per non spaventare nessuno, \u00e8 ora di chiarire la causa per cui siamo stati chiamati \u201ceversivi\u201d.\u00a0 Quando ancora nel XX secolo ho avuto l\u2019intuizione dell\u2019importanza di difendere l\u2019alpeggio con metodo storico, pensavo bisognasse partire da un semplice concetto, che agli occhi di tutti sembrava scontato: le vacche in alpeggio devono [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3742,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-3740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paolo Ciapparelli racconta:La necessit\u00e0 di ribellarsi - Valli del Bitto Trading Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paolo Ciapparelli racconta:La necessit\u00e0 di ribellarsi - Valli del Bitto Trading Spa\" \/>\n<meta property=\"og:description\" content=\"Esistono diverse forme di ribellione: per non spaventare nessuno, \u00e8 ora di chiarire la causa per cui siamo stati chiamati \u201ceversivi\u201d.\u00a0 Quando ancora nel XX secolo ho avuto l\u2019intuizione dell\u2019importanza di difendere l\u2019alpeggio con metodo storico, pensavo bisognasse partire da un semplice concetto, che agli occhi di tutti sembrava scontato: le vacche in alpeggio devono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/\" \/>\n<meta property=\"og:site_name\" content=\"Valli del Bitto Trading Spa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StoricoRibelle\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-30T09:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/11\/vacca-e-vitello-OB-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"grazia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"grazia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/\"},\"author\":{\"name\":\"grazia\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/person\\\/9e6b6c75da11c3dd2fc8903d18995d98\"},\"headline\":\"Paolo Ciapparelli racconta: La necessit\u00e0 di ribellarsi\",\"datePublished\":\"2022-11-30T09:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/vacca-e-vitello-OB-2-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/\",\"name\":\"Paolo Ciapparelli racconta: La necessit\u00e0 di ribellarsi - Valli del Bitto Trading Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/vacca-e-vitello-OB-2-scaled.jpg\",\"datePublished\":\"2022-11-30T09:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/vacca-e-vitello-OB-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/vacca-e-vitello-OB-2-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"vacca e vitello\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/storicoribelle.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paolo Ciapparelli racconta:La necessit\u00e0 di ribellarsi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#website\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/\",\"name\":\"Valli del Bitto Trading Spa\",\"description\":\"Salvaguardia delle tradizioni e dei valori locali\",\"publisher\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/storicoribelle.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#organization\",\"name\":\"Valli del Bitto Trading Spa\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Valli del Bitto Trading Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StoricoRibelle\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/person\\\/9e6b6c75da11c3dd2fc8903d18995d98\",\"name\":\"grazia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g\",\"caption\":\"grazia\"},\"url\":\"https:\\\/\\\/storicoribelle.com\\\/en\\\/author\\\/grazia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paolo Ciapparelli racconta:La necessit\u00e0 di ribellarsi - Valli del Bitto Trading Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/","og_locale":"en_US","og_type":"article","og_title":"Paolo Ciapparelli racconta:La necessit\u00e0 di ribellarsi - Valli del Bitto Trading Spa","og_description":"Esistono diverse forme di ribellione: per non spaventare nessuno, \u00e8 ora di chiarire la causa per cui siamo stati chiamati \u201ceversivi\u201d.\u00a0 Quando ancora nel XX secolo ho avuto l\u2019intuizione dell\u2019importanza di difendere l\u2019alpeggio con metodo storico, pensavo bisognasse partire da un semplice concetto, che agli occhi di tutti sembrava scontato: le vacche in alpeggio devono [&hellip;]","og_url":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/","og_site_name":"Valli del Bitto Trading Spa","article_publisher":"https:\/\/www.facebook.com\/StoricoRibelle\/","article_published_time":"2022-11-30T09:30:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/11\/vacca-e-vitello-OB-2-scaled.jpg","type":"image\/jpeg"}],"author":"grazia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"grazia","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/#article","isPartOf":{"@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/"},"author":{"name":"grazia","@id":"https:\/\/storicoribelle.com\/#\/schema\/person\/9e6b6c75da11c3dd2fc8903d18995d98"},"headline":"Paolo Ciapparelli racconta: La necessit\u00e0 di ribellarsi","datePublished":"2022-11-30T09:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/storicoribelle.com\/#organization"},"image":{"@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/#primaryimage"},"thumbnailUrl":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/11\/vacca-e-vitello-OB-2-scaled.jpg","articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/","url":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/","name":"Paolo Ciapparelli racconta: La necessit\u00e0 di ribellarsi - Valli del Bitto Trading Spa","isPartOf":{"@id":"https:\/\/storicoribelle.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/#primaryimage"},"image":{"@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/#primaryimage"},"thumbnailUrl":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/11\/vacca-e-vitello-OB-2-scaled.jpg","datePublished":"2022-11-30T09:30:00+00:00","breadcrumb":{"@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/#primaryimage","url":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/11\/vacca-e-vitello-OB-2-scaled.jpg","contentUrl":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/11\/vacca-e-vitello-OB-2-scaled.jpg","width":2560,"height":1920,"caption":"vacca e vitello"},{"@type":"BreadcrumbList","@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontala-necessita-di-ribellarsi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/storicoribelle.com\/en\/"},{"@type":"ListItem","position":2,"name":"Paolo Ciapparelli racconta:La necessit\u00e0 di ribellarsi"}]},{"@type":"WebSite","@id":"https:\/\/storicoribelle.com\/#website","url":"https:\/\/storicoribelle.com\/","name":"Valli del Bitto Trading Spa","description":"Salvaguardia delle tradizioni e dei valori locali","publisher":{"@id":"https:\/\/storicoribelle.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/storicoribelle.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/storicoribelle.com\/#organization","name":"Valli del Bitto Trading Spa","url":"https:\/\/storicoribelle.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/storicoribelle.com\/#\/schema\/logo\/image\/","url":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/05\/logo.svg","contentUrl":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/05\/logo.svg","width":1,"height":1,"caption":"Valli del Bitto Trading Spa"},"image":{"@id":"https:\/\/storicoribelle.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StoricoRibelle\/"]},{"@type":"Person","@id":"https:\/\/storicoribelle.com\/#\/schema\/person\/9e6b6c75da11c3dd2fc8903d18995d98","name":"grazia","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g","caption":"grazia"},"url":"https:\/\/storicoribelle.com\/en\/author\/grazia\/"}]}},"_links":{"self":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/posts\/3740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/comments?post=3740"}],"version-history":[{"count":4,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/posts\/3740\/revisions"}],"predecessor-version":[{"id":3784,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/posts\/3740\/revisions\/3784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/media\/3742"}],"wp:attachment":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/media?parent=3740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/categories?post=3740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/tags?post=3740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}