{"id":4443,"date":"2023-03-29T15:05:00","date_gmt":"2023-03-29T13:05:00","guid":{"rendered":"https:\/\/dev.noratech.it\/vallibitto\/?p=4443"},"modified":"2023-03-29T15:05:00","modified_gmt":"2023-03-29T13:05:00","slug":"paolo-ciapparelli-tells-a-storylo-storico-ribelle-una-strategia-vincente","status":"publish","type":"post","link":"https:\/\/storicoribelle.com\/en\/paolo-ciapparelli-tells-a-storylo-storico-ribelle-una-strategia-vincente\/","title":{"rendered":"Paolo Ciapparelli tells a story:<br>Lo Storico Ribelle, una strategia vincente!"},"content":{"rendered":"<div>\n<p><em><span style=\"font-weight: 400; color: #000;\">L\u2019obiettivo primario di questi 25 anni di difesa della produzione storica del Bitto, non era certo quello di contrastare l\u2019ascesa del \u201cnuovo Bitto\u201d (quello DOP), in quanto il sistema agricolo valtellinese stava ricalcando la stessa strada di tutto il resto dell\u2019arco alpino. Fontina, Asiago, ecc. avevano anticipato la tendenza ad usare piccole, realmente tipiche, produzioni storiche, trasformandole in grosse produzioni simil-industriali, mantenendone il nome. Quel che non era previsto \u00e8 stato che congiuntamente all\u2019aumento dei numeri si verificasse un progressivo regresso del prezzo.<\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color: #000;\">Cosa significa tutto questo: \u00e8 la dimostrazione che un formaggio con una reputazione storica, se non mantiene anche solo in piccola parte la propria originalit\u00e0, scade a livello industriale, replicabile ovunque, trascinando l\u2019intera filiera verso una inevitabile economia di sussistenza interamente dipendente dalle finanze pubbliche.<\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color: #000;\">Non ci fosse stata la nostra resistenza casearia, il Bitto, come la Fontina, si sarebbe fatto nell\u2019arco dell\u2019intero anno con etichette di colori diversi a distinguere la produzione invernale dall\u2019estiva.<\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color: #000;\">L\u2019errore descritto sopra \u00e8 oggi evidenziato dal tentativo dell\u2019Asiago di ritornare a qualificare alcune malghe verso la produzione di \u201cAsiago Stravecchio\u201d ben identificabile; credo che l\u2019ispirazione venga da noi tramite la malga aderente al Presidio Slow Food. Mi risulta che questa tendenza sia in atto anche con altri formaggi (Fontina \u201cl\u2019Estrema\u201d), in quanto la garanzia di protezione della DOP non \u00e8 pi\u00f9 sufficiente. <\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color: #000;\">Ricordo come fosse oggi una lettera del Ministero dell\u2019agricoltura che sottolineava \u201cviva preoccupazione\u201d per essere venuto a conoscenza del marchio aggiuntivo \u201cValli del Bitto\u201d, concesso nell\u2019accordo firmato nel 1996 da CTCB, Coldiretti, Comunit\u00e0 montana e noi, poi ribadito nel 2003 con l\u2019aggiunta della Provincia di Sondrio. Venivamo colpiti noi che che, soli nel silenzio istituzionale, difendevamo una conclamata verit\u00e0 storica, e il marchio \u201cValli del Bitto\u201d ci venne tolto stracciando gli accordi firmati dalle -ignare!- istituzioni locali. Slow Food intervenne su mia sollecitazione, in quanto senza differenziazioni non avrebbe avuto senso la sola dicitura \u201cBitto\u201d, che metteva sullo stesso piano due produzioni sostanzialmente diverse.<\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color: #000;\">In quell\u2019occasione ricevetti una telefonata da Piero Sardo, Presidente della Fondazione Slow Food per la biodiversit\u00e0, che dopo tanti anni di collaborazione si dimostra ancora con assoluta certezza principale alleato nel difendere la nostra causa, in cui mi disse che, tolta la dicitura \u201cValli del Bitto\u201d, immediatamente si sarebbe creato il marchio \u201cBitto Storico Presidio Slow Food\u201d, di cui l\u2019associazione stessa si sarebbe fatta garante. Per qualche anno siamo andati avanti, come si dice da noi, de sfros, con il nome che pi\u00f9 ci compete, perch\u00e9 rende giustizia alla storia, finch\u00e9 un bel giorno un nuovo ministro dell\u2019agricoltura invi\u00f2 una lettera a Slow Food in cui, riconoscendo la legittimit\u00e0 e il valore di Pres\u00ecdi, trovava \u201ceccessivamente laudativo\u201d (sic) la parola Storico associata al Bitto. Prima, durante e poi, sembra che il problema pi\u00f9 grave e impellente per l\u2019agricoltura, a parere del Ministero, fosse il Bitto Storico. Il motivo credo fosse il nostro aver colpito nel segno, non essendo evidentemente abituati ad un\u2019opposizione operata da una produzione piccolissima, ma che si era meritata l\u2019attenzione di riviste scientifiche nazionali e internazionali (*vedi note).<\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color: #000;\">Nel frattempo il MiPAF concede ai miei amici del parmigiano Reggiano l\u2019aggiunta \u201cVacche Rosse\u201d, \u00e8 la denominazione aggiuntiva per noi illegale, per altre DOP diventa regolare. Altro peso, altro spessore tra il Consorzio del Parmigiano e quello di Bitto e Casera? Oppure meno accanimento nei riguardi di Catellani, ideatore del \u201cVacche Rosse\u201d, rispetto a Ciapparelli eversivo perch\u00e9 reo di difendere l\u2019erba di pascolo da mangimi e fermenti? Sta di fatto che oggi tutti tendono a differenziarsi per evidenziare l\u2019originalit\u00e0 e la continuit\u00e0 di un prodotto, non per narcisismo, ma a garanzia del futuro della veridicit\u00e0 di un formaggio, anche a tutela dei consumatori. <\/span><\/em><\/p>\n<p><em><span style=\"font-weight: 400; color: #000;\">\u201cStorico Ribelle\u201d \u00e8 diventato un marchio modello per le produzioni artigianali, e per questo ha puntato il dito contro un sistema che ha bisogno di profonda revisione. Attenzione per\u00f2: questo sistema ingessato \u00e8 dotato di anticorpi, e pur di fare come nel \u201cGattopardo\u201d, dove si cambia tutto per non cambiare niente, e ha gi\u00e0 messo gli occhi sul marchio \u201cStorico Ribelle\u201d dato che ha capito, piaccia o no, che la nostra \u00e8 una strategia vincente. Compito nostro \u00e8 di continuare a vigilare, e di chi la pensa come noi, di sostenerci apertamente, in modo visibile.<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400;\">* Un esempio su tutti: \u201cField Study of Relevant Cases of Success: Historical Rebel Cheese (formerly known as Historical Bitto)\u201d, Kedge Business School.<\/span><\/p>\n<\/div>\n<h2>News you might like<\/h2>\n<div>\n<\/div>\n<p>\n    <a href=\"\/vallibitto\/news-ed-eventi\/\">See all News<\/a>\n<\/p>\n<p><!--more--><br \/>\n<!-- {\"name\":\"A-PAGINA-NEWS\",\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"style\":\"default\",\"width\":\"large\",\"vertical_align\":\"middle\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"title_breakpoint\":\"xl\",\"image_position\":\"center-center\",\"padding_remove_bottom\":false,\"animation\":\"fade\"},\"children\":[{\"type\":\"row\",\"props\":{\"width\":\"xsmall\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h1\",\"text_align\":\"center\",\"margin\":\"default\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\"},\"props\":{\"content\":{\"filters\":{\"search\":\"\"},\"name\":\"title\"}}}},{\"type\":\"text\",\"props\":{\"margin\":\"default\",\"column_breakpoint\":\"m\",\"text_align\":\"center\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\"},\"props\":{\"content\":{\"filters\":{\"search\":\"\",\"date\":\"\"},\"name\":\"date\"}}}}]}]},{\"type\":\"row\",\"props\":{\"width\":\"large\",\"margin\":\"large\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"image\",\"props\":{\"margin\":\"default\",\"image_svg_color\":\"emphasis\",\"image_width\":\"1400\",\"image_height\":\"700\",\"animation\":\"none\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\"},\"props\":{\"image\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.url\"},\"image_alt\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.alt\"}}}}]}]},{\"type\":\"row\",\"props\":{\"width\":\"default\",\"margin\":\"large\",\"layout\":\"2-3,1-3\",\"padding_remove_horizontal\":false,\"column_gap\":\"large\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"2-3\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"margin\":\"medium\",\"column_breakpoint\":\"m\",\"animation\":\"none\",\"content\":\"\n\n<p><em><span style=\\\"font-weight: 400; color: #000;\\\">L\\u2019obiettivo primario di questi 25 anni di difesa della produzione storica del Bitto, non era certo quello di contrastare l\\u2019ascesa del \\u201cnuovo Bitto\\u201d (quello DOP), in quanto il sistema agricolo valtellinese stava ricalcando la stessa strada di tutto il resto dell\\u2019arco alpino. Fontina, Asiago, ecc. avevano anticipato la tendenza ad usare piccole, realmente tipiche, produzioni storiche, trasformandole in grosse produzioni simil-industriali, mantenendone il nome. Quel che non era previsto \\u00e8 stato che congiuntamente all\\u2019aumento dei numeri si verificasse un progressivo regresso del prezzo.<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color: #000;\\\">Cosa significa tutto questo: \\u00e8 la dimostrazione che un formaggio con una reputazione storica, se non mantiene anche solo in piccola parte la propria originalit\\u00e0, scade a livello industriale, replicabile ovunque, trascinando l\\u2019intera filiera verso una inevitabile economia di sussistenza interamente dipendente dalle finanze pubbliche.<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color: #000;\\\">Non ci fosse stata la nostra resistenza casearia, il Bitto, come la Fontina, si sarebbe fatto nell\\u2019arco dell\\u2019intero anno con etichette di colori diversi a distinguere la produzione invernale dall\\u2019estiva.<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color: #000;\\\">L\\u2019errore descritto sopra \\u00e8 oggi evidenziato dal tentativo dell\\u2019Asiago di ritornare a qualificare alcune malghe verso la produzione di \\u201cAsiago Stravecchio\\u201d ben identificabile; credo che l\\u2019ispirazione venga da noi tramite la malga aderente al Presidio Slow Food. Mi risulta che questa tendenza sia in atto anche con altri formaggi (Fontina \\u201cl\\u2019Estrema\\u201d), in quanto la garanzia di protezione della DOP non \\u00e8 pi\\u00f9 sufficiente.\\u00a0<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color: #000;\\\">Ricordo come fosse oggi una lettera del Ministero dell\\u2019agricoltura che sottolineava \\u201cviva preoccupazione\\u201d per essere venuto a conoscenza del marchio aggiuntivo \\u201cValli del Bitto\\u201d, concesso nell\\u2019accordo firmato nel 1996 da CTCB, Coldiretti, Comunit\\u00e0 montana e noi, poi ribadito nel 2003 con l\\u2019aggiunta della Provincia di Sondrio. Venivamo colpiti noi che che, soli nel silenzio istituzionale, difendevamo una conclamata verit\\u00e0 storica, e il marchio \\u201cValli del Bitto\\u201d ci venne tolto stracciando gli accordi firmati dalle -ignare!- istituzioni locali. Slow Food intervenne su mia sollecitazione, in quanto senza differenziazioni non avrebbe avuto senso la sola dicitura \\u201cBitto\\u201d, che metteva sullo stesso piano due produzioni sostanzialmente diverse.<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color: #000;\\\">In quell\\u2019occasione ricevetti una telefonata da Piero Sardo, Presidente della Fondazione Slow Food per la biodiversit\\u00e0, che dopo tanti anni di collaborazione si dimostra ancora con assoluta certezza principale alleato nel difendere la nostra causa, in cui mi disse che, tolta la dicitura \\u201cValli del Bitto\\u201d, immediatamente si sarebbe creato il marchio \\u201cBitto Storico Presidio Slow Food\\u201d, di cui l\\u2019associazione stessa si sarebbe fatta garante. Per qualche anno siamo andati avanti, come si dice da noi, de sfros, con il nome che pi\\u00f9 ci compete, perch\\u00e9 rende giustizia alla storia, finch\\u00e9 un bel giorno un nuovo ministro dell\\u2019agricoltura invi\\u00f2 una lettera a Slow Food in cui, riconoscendo la legittimit\\u00e0 e il valore di Pres\\u00ecdi, trovava \\u201ceccessivamente laudativo\\u201d (sic) la parola Storico associata al Bitto. Prima, durante e poi, sembra che il problema pi\\u00f9 grave e impellente per l\\u2019agricoltura, a parere del Ministero, fosse il Bitto Storico. Il motivo credo fosse il nostro aver colpito nel segno, non essendo evidentemente abituati ad un\\u2019opposizione operata da una produzione piccolissima, ma che si era meritata l\\u2019attenzione di riviste scientifiche nazionali e internazionali (*vedi note).<\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color: #000;\\\">Nel frattempo il MiPAF concede ai miei amici del parmigiano Reggiano l\\u2019aggiunta \\u201cVacche Rosse\\u201d, \\u00e8 la denominazione aggiuntiva per noi illegale, per altre DOP diventa regolare. Altro peso, altro spessore tra il Consorzio del Parmigiano e quello di Bitto e Casera? Oppure meno accanimento nei riguardi di Catellani, ideatore del \\u201cVacche Rosse\\u201d, rispetto a Ciapparelli eversivo perch\\u00e9 reo di difendere l\\u2019erba di pascolo da mangimi e fermenti? Sta di fatto che oggi tutti tendono a differenziarsi per evidenziare l\\u2019originalit\\u00e0 e la continuit\\u00e0 di un prodotto, non per narcisismo, ma a garanzia del futuro della veridicit\\u00e0 di un formaggio, anche a tutela dei consumatori. <\\\/span><\\\/em><\\\/p>\\n\n\n<p><em><span style=\\\"font-weight: 400; color: #000;\\\">\\u201cStorico Ribelle\\u201d \\u00e8 diventato un marchio modello per le produzioni artigianali, e per questo ha puntato il dito contro un sistema che ha bisogno di profonda revisione. Attenzione per\\u00f2: questo sistema ingessato \\u00e8 dotato di anticorpi, e pur di fare come nel \\u201cGattopardo\\u201d, dove si cambia tutto per non cambiare niente, e ha gi\\u00e0 messo gli occhi sul marchio \\u201cStorico Ribelle\\u201d dato che ha capito, piaccia o no, che la nostra \\u00e8 una strategia vincente. Compito nostro \\u00e8 di continuare a vigilare, e di chi la pensa come noi, di sostenerci apertamente, in modo visibile.<\\\/span><\\\/em><\\\/p>\\n\n\n<p><span style=\\\"font-weight: 400;\\\">* Un esempio su tutti: \\u201cField Study of Relevant Cases of Success: Historical Rebel Cheese (formerly known as Historical Bitto)\\u201d, Kedge Business School.<\\\/span><\\\/p>\",\"text_align\":\"left\",\"text_align_breakpoint\":\"m\",\"text_align_fallback\":\"justify\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"media_overlay_gradient\":\"\",\"width_medium\":\"1-3\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"title_element\":\"h2\",\"content\":\"Articoli che potrebbero interessarti\",\"title_style\":\"h4\",\"animation\":\"none\",\"_condition\":true,\"text_align\":\"left\",\"text_align_breakpoint\":\"m\",\"text_align_fallback\":\"center\",\"margin\":\"large\"}},{\"type\":\"grid\",\"props\":{\"show_title\":true,\"show_meta\":true,\"show_content\":true,\"show_image\":true,\"show_link\":true,\"grid_default\":\"1\",\"grid_medium\":\"1\",\"filter_style\":\"tab\",\"filter_all\":true,\"filter_position\":\"top\",\"filter_align\":\"left\",\"filter_grid_width\":\"auto\",\"filter_grid_breakpoint\":\"m\",\"title_hover_style\":\"reset\",\"title_element\":\"h3\",\"title_align\":\"top\",\"title_grid_width\":\"1-2\",\"title_grid_breakpoint\":\"m\",\"meta_style\":\"h6\",\"meta_align\":\"above-title\",\"meta_element\":\"div\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"left\",\"image_grid_width\":\"auto\",\"image_grid_breakpoint\":\"\",\"image_svg_color\":\"emphasis\",\"link_text\":\"\",\"link_style\":\"default\",\"margin\":\"default\",\"item_animation\":true,\"grid_column_gap\":\"small\",\"image_width\":\"100\",\"image_grid_column_gap\":\"small\",\"image_vertical_align\":true,\"title_style\":\"h5\",\"meta_color\":\"primary\",\"title_margin\":\"remove\",\"grid_row_gap\":\"small\",\"panel_link\":false,\"grid_small\":\"2\",\"grid_divider\":true,\"title_link\":true,\"image_link\":true,\"animation\":\"none\",\"image_height\":\"70\"},\"children\":[{\"type\":\"grid_item\",\"source\":{\"query\":{\"name\":\"posts.customPosts\",\"arguments\":{\"terms\":[24],\"category_operator\":\"IN\",\"post_tag_operator\":\"IN\",\"users\":[],\"users_operator\":\"IN\",\"offset\":0,\"limit\":4,\"order\":\"rand\",\"order_direction\":\"DESC\"}},\"props\":{\"title\":{\"filters\":{\"search\":\"\"},\"name\":\"title\"},\"image\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.url\"},\"image_alt\":{\"filters\":{\"search\":\"\"},\"name\":\"featuredImage.alt\"},\"link\":{\"filters\":{\"search\":\"\"},\"name\":\"link\"}}}}],\"modified\":\"2020-12-14T10:54:26.407Z\",\"name\":\"\"},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin\":\"medium\",\"text_align\":\"left\",\"text_align_breakpoint\":\"m\",\"text_align_fallback\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"text\",\"icon_align\":\"right\",\"content\":\"Vedi tutte le News\",\"icon\":\"chevron-right\",\"link\":\"news-ed-eventi\\\/\"}}]}]}]}],\"name\":\"articolo\"}],\"version\":\"2.7.26\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019obiettivo primario di questi 25 anni di difesa della produzione storica del Bitto, non era certo quello di contrastare l\u2019ascesa del \u201cnuovo Bitto\u201d (quello DOP), in quanto il sistema agricolo valtellinese stava ricalcando la stessa strada di tutto il resto dell\u2019arco alpino. Fontina, Asiago, ecc. avevano anticipato la tendenza ad usare piccole, realmente tipiche, produzioni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4443","post","type-post","status-publish","format-standard","hentry","category-news-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paolo Ciapparelli tells a story:Lo Storico Ribelle, una strategia vincente! - Valli del Bitto Trading Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paolo Ciapparelli tells a story:Lo Storico Ribelle, una strategia vincente! - Valli del Bitto Trading Spa\" \/>\n<meta property=\"og:description\" content=\"L\u2019obiettivo primario di questi 25 anni di difesa della produzione storica del Bitto, non era certo quello di contrastare l\u2019ascesa del \u201cnuovo Bitto\u201d (quello DOP), in quanto il sistema agricolo valtellinese stava ricalcando la stessa strada di tutto il resto dell\u2019arco alpino. Fontina, Asiago, ecc. avevano anticipato la tendenza ad usare piccole, realmente tipiche, produzioni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/\" \/>\n<meta property=\"og:site_name\" content=\"Valli del Bitto Trading Spa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StoricoRibelle\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-29T13:05:00+00:00\" \/>\n<meta name=\"author\" content=\"grazia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"grazia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\\\/\"},\"author\":{\"name\":\"grazia\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/person\\\/9e6b6c75da11c3dd2fc8903d18995d98\"},\"headline\":\"Paolo Ciapparelli tells a story: Lo Storico Ribelle, una strategia vincente!\",\"datePublished\":\"2023-03-29T13:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\\\/\"},\"wordCount\":758,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\\\/\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\\\/\",\"name\":\"Paolo Ciapparelli tells a story: Lo Storico Ribelle, una strategia vincente! - Valli del Bitto Trading Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#website\"},\"datePublished\":\"2023-03-29T13:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/storicoribelle.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paolo Ciapparelli tells a story:Lo Storico Ribelle, una strategia vincente!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#website\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/\",\"name\":\"Valli del Bitto Trading Spa\",\"description\":\"Salvaguardia delle tradizioni e dei valori locali\",\"publisher\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/storicoribelle.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#organization\",\"name\":\"Valli del Bitto Trading Spa\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Valli del Bitto Trading Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StoricoRibelle\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/person\\\/9e6b6c75da11c3dd2fc8903d18995d98\",\"name\":\"grazia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g\",\"caption\":\"grazia\"},\"url\":\"https:\\\/\\\/storicoribelle.com\\\/en\\\/author\\\/grazia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paolo Ciapparelli tells a story:Lo Storico Ribelle, una strategia vincente! - Valli del Bitto Trading Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/","og_locale":"en_US","og_type":"article","og_title":"Paolo Ciapparelli tells a story:Lo Storico Ribelle, una strategia vincente! - Valli del Bitto Trading Spa","og_description":"L\u2019obiettivo primario di questi 25 anni di difesa della produzione storica del Bitto, non era certo quello di contrastare l\u2019ascesa del \u201cnuovo Bitto\u201d (quello DOP), in quanto il sistema agricolo valtellinese stava ricalcando la stessa strada di tutto il resto dell\u2019arco alpino. Fontina, Asiago, ecc. avevano anticipato la tendenza ad usare piccole, realmente tipiche, produzioni [&hellip;]","og_url":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/","og_site_name":"Valli del Bitto Trading Spa","article_publisher":"https:\/\/www.facebook.com\/StoricoRibelle\/","article_published_time":"2023-03-29T13:05:00+00:00","author":"grazia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"grazia","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/#article","isPartOf":{"@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/"},"author":{"name":"grazia","@id":"https:\/\/storicoribelle.com\/#\/schema\/person\/9e6b6c75da11c3dd2fc8903d18995d98"},"headline":"Paolo Ciapparelli tells a story: Lo Storico Ribelle, una strategia vincente!","datePublished":"2023-03-29T13:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/"},"wordCount":758,"commentCount":0,"publisher":{"@id":"https:\/\/storicoribelle.com\/#organization"},"articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/","url":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/","name":"Paolo Ciapparelli tells a story: Lo Storico Ribelle, una strategia vincente! - Valli del Bitto Trading Spa","isPartOf":{"@id":"https:\/\/storicoribelle.com\/#website"},"datePublished":"2023-03-29T13:05:00+00:00","breadcrumb":{"@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/storicoribelle.com\/paolo-ciapparelli-raccontalo-storico-ribelle-una-strategia-vincente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/storicoribelle.com\/en\/"},{"@type":"ListItem","position":2,"name":"Paolo Ciapparelli tells a story:Lo Storico Ribelle, una strategia vincente!"}]},{"@type":"WebSite","@id":"https:\/\/storicoribelle.com\/#website","url":"https:\/\/storicoribelle.com\/","name":"Valli del Bitto Trading Spa","description":"Salvaguardia delle tradizioni e dei valori locali","publisher":{"@id":"https:\/\/storicoribelle.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/storicoribelle.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/storicoribelle.com\/#organization","name":"Valli del Bitto Trading Spa","url":"https:\/\/storicoribelle.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/storicoribelle.com\/#\/schema\/logo\/image\/","url":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/05\/logo.svg","contentUrl":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/05\/logo.svg","width":1,"height":1,"caption":"Valli del Bitto Trading Spa"},"image":{"@id":"https:\/\/storicoribelle.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StoricoRibelle\/"]},{"@type":"Person","@id":"https:\/\/storicoribelle.com\/#\/schema\/person\/9e6b6c75da11c3dd2fc8903d18995d98","name":"grazia","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2230d21c7715bafd41feab3eb50b3397252b8a5ccca3301dd1883c2905571757?s=96&d=mm&r=g","caption":"grazia"},"url":"https:\/\/storicoribelle.com\/en\/author\/grazia\/"}]}},"_links":{"self":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/posts\/4443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/comments?post=4443"}],"version-history":[{"count":0,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/posts\/4443\/revisions"}],"wp:attachment":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/media?parent=4443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/categories?post=4443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/tags?post=4443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}