{"id":633,"date":"2022-05-12T17:20:04","date_gmt":"2022-05-12T15:20:04","guid":{"rendered":"https:\/\/dev.noratech.it\/vallibitto\/?post_type=product&#038;p=633"},"modified":"2023-10-02T17:38:33","modified_gmt":"2023-10-02T15:38:33","slug":"storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg","status":"publish","type":"product","link":"https:\/\/storicoribelle.com\/en\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/","title":{"rendered":"Storico Ribelle Presidio Slow Food annata 2018 alpe Cavizzola &#8211; 1 kg."},"content":{"rendered":"<p>Lo Storico Ribelle viene prodotto esclusivamente nei mesi estivi in alpeggio:il bestiame costituito da vacche da latte ( tradizionalmente di razza bruno alpina) e da capre (di razza orobica autoctona della Valgerola) viene condotto sui pascoli nel mese di giugno e vi resta, condizioni climatiche permettendo, fino al mese di settembre.<br \/>\nI bovini e i caprini si nutrono esclusivamente del pascolo alpino, da disciplinare infatti \u00e8 vietato integrare l\u2019alimentazione con mangimi e insilati; l&#8217;ambiente delle prealpi Orobie, per esposizione, per la abbondanza di corsi d\u2019 acqua e per le variazioni altimetriche, presenta una variet\u00e0 floreale che conferisce al latte propriet\u00e0 nutrizionali di qualit\u00e0 superiore.<br \/>\nLa biodiversit\u00e0 dell\u2019ambiente montano, i suoi profumi ed aromi, conferiscono caratteristiche organolettiche uniche a ciascuna forma di Storico prodotta negli alpeggi aderenti al Consorzio di Salvaguardia.<br \/>\nL&#8217;alpeggio Cavizzola si trova in Val Brembana, sul versante bergamasco del passo di S.Marco.<br \/>\nIl formaggio qui prodotto, generalmente, ha un sapore marcato dato dalla quantit\u00e0 di latte di capra utilizzato (15%- 20 %) nonostante questo mantiene la sua dolcezza e la richezza di note floreali data dalla particolarit\u00e0 del pascolo, a volte, specialmente nella stagionatura si ritrovano note di torba, liquirizia e caff\u00e8.<\/p>\n<p>L&#8217;alpe Cavizzola \u00e8 caricata da Alfio Sassella con la moglie Sonia e l&#8217;esperto casaro Fortunato, \u00e8 un&#8217;autentica alpe di una volta! Dove ci si muove lentamente, a piedi e a cavallo, per raggiungere l&#8217;angolo pi\u00f9 nascosto delle Orobie&#8230; Qui, pi\u00f9 che altrove, si trovano solo capre Orobiche e vacche Brune Alpine Originali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peso netto da 950g. a 1050g.<\/p>\n<p>Confezionato sottovuoto<br \/>\nDa consumarsi preferibilmente entro 150 gg.<\/p>\n<p>Valori nutrizionali per 100 gr:<br \/>\nenergia (kj) 1716<br \/>\nkcal 413<br \/>\nGrassi (g) 33<br \/>\ndi cui acidi grassi saturi (g) 23<br \/>\nCarboidrati (g) 1,9<br \/>\ndi cui zuccheri (g) 0<br \/>\nProteine (g) 27<br \/>\nSale (g) 1,3<\/p>\n","protected":false},"featured_media":4175,"template":"","meta":[],"product_brand":[],"product_cat":[20],"product_tag":[],"class_list":{"0":"post-633","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-stagionato","8":"first","9":"outofstock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Storico Ribelle Presidio Slow Food annata 2018 alpe Cavizzola - 1 kg. - Valli del Bitto Trading Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storico Ribelle Presidio Slow Food annata 2018 alpe Cavizzola - 1 kg. - Valli del Bitto Trading Spa\" \/>\n<meta property=\"og:description\" content=\"Peso netto da 950g. a 1050g.  Confezionato sottovuoto Da consumarsi preferibilmente entro 150 gg.  Valori nutrizionali per 100 gr: energia (kj) 1716 kcal 413 Grassi (g) 33 di cui acidi grassi saturi (g) 23 Carboidrati (g) 1,9 di cui zuccheri (g) 0 Proteine (g) 27 Sale (g) 1,3\" \/>\n<meta property=\"og:url\" content=\"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/\" \/>\n<meta property=\"og:site_name\" content=\"Valli del Bitto Trading Spa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StoricoRibelle\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-02T15:38:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/09\/Storico-Ribelle-2010_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/prodotto\\\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\\\/\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/prodotto\\\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\\\/\",\"name\":\"Storico Ribelle Presidio Slow Food annata 2018 alpe Cavizzola - 1 kg. - Valli del Bitto Trading Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/prodotto\\\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/prodotto\\\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Storico-Ribelle-2010_3.jpg\",\"datePublished\":\"2022-05-12T15:20:04+00:00\",\"dateModified\":\"2023-10-02T15:38:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/prodotto\\\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/storicoribelle.com\\\/prodotto\\\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/prodotto\\\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Storico-Ribelle-2010_3.jpg\",\"contentUrl\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Storico-Ribelle-2010_3.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"SAMSUNG CSC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/prodotto\\\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/storicoribelle.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/storicoribelle.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Storico Ribelle Presidio Slow Food annata 2018 alpe Cavizzola &#8211; 1 kg.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#website\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/\",\"name\":\"Valli del Bitto Trading Spa\",\"description\":\"Salvaguardia delle tradizioni e dei valori locali\",\"publisher\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/storicoribelle.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#organization\",\"name\":\"Valli del Bitto Trading Spa\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/storicoribelle.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Valli del Bitto Trading Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/storicoribelle.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StoricoRibelle\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Storico Ribelle Presidio Slow Food annata 2018 alpe Cavizzola - 1 kg. - Valli del Bitto Trading Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/","og_locale":"en_US","og_type":"article","og_title":"Storico Ribelle Presidio Slow Food annata 2018 alpe Cavizzola - 1 kg. - Valli del Bitto Trading Spa","og_description":"Peso netto da 950g. a 1050g.  Confezionato sottovuoto Da consumarsi preferibilmente entro 150 gg.  Valori nutrizionali per 100 gr: energia (kj) 1716 kcal 413 Grassi (g) 33 di cui acidi grassi saturi (g) 23 Carboidrati (g) 1,9 di cui zuccheri (g) 0 Proteine (g) 27 Sale (g) 1,3","og_url":"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/","og_site_name":"Valli del Bitto Trading Spa","article_publisher":"https:\/\/www.facebook.com\/StoricoRibelle\/","article_modified_time":"2023-10-02T15:38:33+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/09\/Storico-Ribelle-2010_3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/","url":"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/","name":"Storico Ribelle Presidio Slow Food annata 2018 alpe Cavizzola - 1 kg. - Valli del Bitto Trading Spa","isPartOf":{"@id":"https:\/\/storicoribelle.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/#primaryimage"},"image":{"@id":"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/#primaryimage"},"thumbnailUrl":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/09\/Storico-Ribelle-2010_3.jpg","datePublished":"2022-05-12T15:20:04+00:00","dateModified":"2023-10-02T15:38:33+00:00","breadcrumb":{"@id":"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/#primaryimage","url":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/09\/Storico-Ribelle-2010_3.jpg","contentUrl":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/09\/Storico-Ribelle-2010_3.jpg","width":1024,"height":1024,"caption":"SAMSUNG CSC"},{"@type":"BreadcrumbList","@id":"https:\/\/storicoribelle.com\/prodotto\/storico-ribelle-presidio-slow-food-annata-2018-alpe-cavizzola-1-kg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/storicoribelle.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/storicoribelle.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Storico Ribelle Presidio Slow Food annata 2018 alpe Cavizzola &#8211; 1 kg."}]},{"@type":"WebSite","@id":"https:\/\/storicoribelle.com\/#website","url":"https:\/\/storicoribelle.com\/","name":"Valli del Bitto Trading Spa","description":"Salvaguardia delle tradizioni e dei valori locali","publisher":{"@id":"https:\/\/storicoribelle.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/storicoribelle.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/storicoribelle.com\/#organization","name":"Valli del Bitto Trading Spa","url":"https:\/\/storicoribelle.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/storicoribelle.com\/#\/schema\/logo\/image\/","url":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/05\/logo.svg","contentUrl":"https:\/\/storicoribelle.com\/wp-content\/uploads\/2022\/05\/logo.svg","width":1,"height":1,"caption":"Valli del Bitto Trading Spa"},"image":{"@id":"https:\/\/storicoribelle.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StoricoRibelle\/"]}]}},"_links":{"self":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/product\/633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/media\/4175"}],"wp:attachment":[{"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/media?parent=633"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/product_brand?post=633"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/product_cat?post=633"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/storicoribelle.com\/en\/wp-json\/wp\/v2\/product_tag?post=633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}